{"id":3094,"date":"2024-12-05T07:16:35","date_gmt":"2024-12-05T07:16:35","guid":{"rendered":"https:\/\/gneealloy.com\/?post_type=product&#038;p=3094"},"modified":"2025-02-14T16:18:17","modified_gmt":"2025-02-14T08:18:17","slug":"inconel-plate","status":"publish","type":"product","link":"https:\/\/gneealloy.com\/pt\/products\/inconel-plate\/","title":{"rendered":"Fabricante de placas de Inconel"},"content":{"rendered":"<p>A placa de Inconel \u00e9 uma placa de liga de n\u00edquel de alto desempenho, projetada para ambientes extremos que exigem excepcional resist\u00eancia \u00e0 corros\u00e3o, resist\u00eancia a altas temperaturas e resist\u00eancia \u00e0 oxida\u00e7\u00e3o. \u00c9 composta principalmente de n\u00edquel (tipicamente acima de 50%) com quantidades vari\u00e1veis de cromo, ferro, molibd\u00eanio e outros elementos.<\/p>\n<p>S\u00e3o amplamente utilizados em ind\u00fastrias como a aeroespacial, de processamento qu\u00edmico e de engenharia naval, onde a exposi\u00e7\u00e3o a condi\u00e7\u00f5es extremas \u00e9 comum. Podem suportar temperaturas que variam de n\u00edveis criog\u00eanicos at\u00e9 1204 \u00b0C (2200 \u00b0F) sem perder sua integridade estrutural ou propriedades mec\u00e2nicas.<\/p>\n<h2>Quais s\u00e3o os formatos fornecidos pelo fornecedor de chapas de Inconel da Gnee?<\/h2>\n<ul>\n<li>Chapa de Inconel laminada a quente<\/li>\n<li>Chapa de Inconel laminada a frio<\/li>\n<li>Chapa de Inconel<\/li>\n<li>Bobina de Inconel<\/li>\n<li>Tira de Inconel<\/li>\n<li>Placa de Inconel para trocador de calor<\/li>\n<li>Placa de Inconel para componentes de turbina<\/li>\n<li>Placa de Inconel para equipamentos qu\u00edmicos<\/li>\n<li>Placa de Inconel para gera\u00e7\u00e3o de energia<\/li>\n<li>Placa fina de Inconel<\/li>\n<li>Placa espessa de Inconel<\/li>\n<li>Placa de Inconel brilhante<\/li>\n<li>Placa de Inconel escovado<\/li>\n<li>Placa de Inconel polida<\/li>\n<\/ul>\n<h2>Par\u00e2metros do produto de chapa met\u00e1lica Inconel<\/h2>\n<table style=\"border-collapse: collapse; width: 1018px; height: 391px;\" border=\"0\" width=\"829\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt; width: 206.25pt;\" width=\"275\" height=\"18\">Par\u00e2metro<\/td>\n<td style=\"width: 415.50pt;\" width=\"554\">Descri\u00e7\u00e3o<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt;\" height=\"18\">Graus de materiais<\/td>\n<td>Inconel 600, 625, 718, 800, 825, X-750<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt;\" height=\"18\">Dimens\u00f5es<\/td>\n<td>Espessura: 1 mm a 100 mm, Largura: 100 mm a 2000 mm, Comprimento: at\u00e9 12 m<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt;\" height=\"18\">Processo de fabrica\u00e7\u00e3o<\/td>\n<td>Laminado a quente, laminado a frio, cortado sob medida, tratado termicamente<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt;\" height=\"18\">Acabamento da superf\u00edcie<\/td>\n<td>Brilhante, escovado, polido<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt;\" height=\"18\">Composi\u00e7\u00e3o Qu\u00edmica<\/td>\n<td>Ni: 58\u201372%, Cr: 14\u201323%, Fe: \u22645%, Mo: 3\u201310%, Nb: 1\u20133%<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt;\" height=\"18\">Resist\u00eancia \u00e0 trac\u00e7\u00e3o<\/td>\n<td>520 MPa\u20131.300 MPa (dependendo da classe)<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt;\" height=\"18\">Resist\u00eancia ao Escoamento<\/td>\n<td>250 MPa\u20131.000 MPa (dependendo da classe)<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt;\" height=\"18\">Alongamento<\/td>\n<td>35%\u201355% (dependendo da nota)<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt;\" height=\"18\">Densidade<\/td>\n<td>8,9 g\/cm\u00b3<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt;\" height=\"18\">Ponto de fus\u00e3o<\/td>\n<td>1.300\u00b0C\u20131.400\u00b0C (dependendo da liga)<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt;\" height=\"18\">Resist\u00eancia \u00e0 temperatura<\/td>\n<td>At\u00e9 1.000\u00b0C<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt;\" height=\"18\">Aplica\u00e7\u00f5es<\/td>\n<td>Aeroespacial, Gera\u00e7\u00e3o de Energia, Processamento Qu\u00edmico, Marinha, Nuclear<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Chapas de liga Inconel de graus comuns em estoque<\/h2>\n<table style=\"border-collapse: collapse; width: 573.77pt;\" border=\"0\" width=\"765\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt; width: 191.25pt;\" width=\"255\" height=\"18\">Nota<\/td>\n<td class=\"et2\" style=\"width: 191.25pt;\" width=\"255\">ASTM\/UNS<\/td>\n<td class=\"et2\" style=\"width: 191.25pt;\" width=\"255\">EN<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\"><a href=\"https:\/\/gneealloy.com\/pt\/products\/inconel-600\/\">Inconel 600<\/a><\/td>\n<td class=\"et2\">UNS N06600<\/td>\n<td class=\"et2\">2.4816<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\"><a href=\"https:\/\/gneealloy.com\/pt\/products\/inconel-601\/\">Inconel 601<\/a><\/td>\n<td class=\"et2\">UNS N06601<\/td>\n<td class=\"et2\">2.4851<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\"><a href=\"https:\/\/gneealloy.com\/pt\/products\/inconel-625\/\">Inconel 625<\/a><\/td>\n<td class=\"et2\">UNS N06625<\/td>\n<td class=\"et2\">2.4856<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\"><a href=\"https:\/\/gneealloy.com\/pt\/products\/inconel-690\/\">Inconel 690<\/a><\/td>\n<td class=\"et2\">UNS N06690<\/td>\n<td class=\"et2\">2.4642<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\"><a href=\"https:\/\/gneealloy.com\/pt\/products\/inconel-718\/\">Inconel 718<\/a><\/td>\n<td class=\"et2\">UNS N07718<\/td>\n<td class=\"et2\">2.4668<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\"><a href=\"https:\/\/gneealloy.com\/pt\/products\/inconel-725\/\">Inconel 725<\/a><\/td>\n<td class=\"et2\">UNS N07725<\/td>\n<td class=\"et2\">N \/ D<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\"><a href=\"https:\/\/gneealloy.com\/pt\/products\/inconel-x-750\/\">Inconel X-750<\/a><\/td>\n<td class=\"et2\">UNS N07750<\/td>\n<td class=\"et2\">2.4669<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Quais s\u00e3o as normas ASTM que um fornecedor de chapas de Inconel da Gnee pode produzir?<\/h2>\n<table style=\"border-collapse: collapse; width: 583.52pt;\" border=\"0\" width=\"778\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt; width: 191.25pt;\" width=\"255\" height=\"18\">Norma ASTM<\/td>\n<td style=\"width: 392.25pt;\" width=\"523\">Descri\u00e7\u00e3o<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt;\" height=\"18\">ASTM B443<\/td>\n<td>Especifica\u00e7\u00f5es para placas de Inconel 625 e 718<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt;\" height=\"18\">ASTM B168<\/td>\n<td>Especifica\u00e7\u00f5es para placas de Inconel 600 e 601<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt;\" height=\"18\">ASTM B409<\/td>\n<td>Especifica\u00e7\u00f5es para chapas de Incoloy 800, 800H e 800HT<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt;\" height=\"18\">ASTM B424<\/td>\n<td>Especifica\u00e7\u00f5es para placas de Incoloy 825<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt;\" height=\"18\">ASTM B670<\/td>\n<td>Especifica\u00e7\u00f5es para placas de Inconel X-750<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt;\" height=\"18\">ASTM B906<\/td>\n<td>Especifica\u00e7\u00e3o para placas de Inconel 690<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Placas de liga Inconel de alta qualidade em diversos tamanhos \u00e0 sua escolha.<\/h2>\n<h3>Chapa de Inconel laminada a frio<\/h3>\n<table style=\"border-collapse: collapse; width: 387.02pt;\" border=\"0\" width=\"516\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt; width: 129.00pt;\" width=\"172\" height=\"18\">Espessura (mm)<\/td>\n<td style=\"width: 129.00pt;\" width=\"172\">Largura (mm)<\/td>\n<td style=\"width: 129.00pt;\" width=\"172\">Comprimento (mm)<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt;\" height=\"18\">0,3 \u2013 3,0<\/td>\n<td>1000 \u2013 1500<\/td>\n<td>2000 \u2013 3000<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>Chapa de Inconel laminada a quente<\/h3>\n<table style=\"border-collapse: collapse; width: 387.02pt;\" border=\"0\" width=\"516\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt; width: 129.00pt;\" width=\"172\" height=\"18\">Espessura (mm)<\/td>\n<td style=\"width: 129.00pt;\" width=\"172\">Largura (mm)<\/td>\n<td style=\"width: 129.00pt;\" width=\"172\">Comprimento (mm)<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt;\" height=\"18\">4,0 \u2013 12,0<\/td>\n<td>1000 \u2013 2000<\/td>\n<td>2000 \u2013 6000<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt;\" height=\"18\">14,0 \u2013 50,0<\/td>\n<td>1000 \u2013 2500<\/td>\n<td>2000 \u2013 6000<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt;\" height=\"18\">60,0 \u2013 100,0<\/td>\n<td>1000 \u2013 3000<\/td>\n<td>2000 \u2013 6000<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>(Tamanhos personalizados dispon\u00edveis mediante solicita\u00e7\u00e3o)<\/p>","protected":false},"excerpt":{"rendered":"<p>A Gnee fabrica e fornece placas de Inconel em <a href=\"https:\/\/gneealloy.com\/pt\/products\/inconel-600\/\">notas 600<\/a>, <a href=\"https:\/\/gneealloy.com\/pt\/products\/inconel-625\/\">625<\/a>, e<a href=\"https:\/\/gneealloy.com\/pt\/products\/inconel-718\/\"> 718<\/a>, Conhecidas por sua alta resist\u00eancia a temperaturas extremas, corros\u00e3o e oxida\u00e7\u00e3o, nossas chapas s\u00e3o ideais para os setores aeroespacial, naval, de usinas de energia e de processamento qu\u00edmico. Atendemos \u00e0s normas ASTM, ASME e ISO, e testes de terceiros est\u00e3o dispon\u00edveis.<br \/>\nOferecemos espessuras de 3 mm a 100 mm, larguras de at\u00e9 2500 mm e tamanhos personalizados. Nossos servi\u00e7os de processamento incluem corte, dobra, fura\u00e7\u00e3o, soldagem e tratamentos de superf\u00edcie. Com envios r\u00e1pidos para toda a Europa, Sudeste Asi\u00e1tico, Oriente M\u00e9dio e Am\u00e9rica Latina, garantimos a entrega no prazo. Entre em contato conosco hoje mesmo para solicitar um or\u00e7amento!<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-4258 size-full\" src=\"https:\/\/gneealloy.com\/wp-content\/uploads\/2024\/12\/Certificate-1.jpg\" alt=\"Certificado\" width=\"830\" height=\"100\" srcset=\"https:\/\/gneealloy.com\/wp-content\/uploads\/2024\/12\/Certificate-1.jpg 830w, https:\/\/gneealloy.com\/wp-content\/uploads\/2024\/12\/Certificate-1-300x36.jpg 300w, https:\/\/gneealloy.com\/wp-content\/uploads\/2024\/12\/Certificate-1-768x93.jpg 768w, https:\/\/gneealloy.com\/wp-content\/uploads\/2024\/12\/Certificate-1-18x2.jpg 18w, https:\/\/gneealloy.com\/wp-content\/uploads\/2024\/12\/Certificate-1-820x100.jpg 820w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><\/p>","protected":false},"featured_media":3162,"template":"","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"default","_kad_post_title":"","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"default","_kad_post_vertical_padding":"default","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"product_brand":[],"product_cat":[83],"product_tag":[101,116],"class_list":["post-3094","product","type-product","status-publish","has-post-thumbnail","product_cat-inconel","product_tag-inconel-shape","product_tag-land-page","first","instock","shipping-taxable","product-type-simple","entry","content-bg","loop-entry"],"taxonomy_info":{"product_cat":[{"value":83,"label":"Inconel"}],"product_tag":[{"value":101,"label":"Inconel Shape"},{"value":116,"label":"Land Page"}]},"featured_image_src_large":["https:\/\/gneealloy.com\/wp-content\/uploads\/2024\/12\/Inconel-Plate-2.jpg",800,600,false],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/gneealloy.com\/pt\/wp-json\/wp\/v2\/product\/3094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gneealloy.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gneealloy.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gneealloy.com\/pt\/wp-json\/wp\/v2\/media\/3162"}],"wp:attachment":[{"href":"https:\/\/gneealloy.com\/pt\/wp-json\/wp\/v2\/media?parent=3094"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gneealloy.com\/pt\/wp-json\/wp\/v2\/product_brand?post=3094"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gneealloy.com\/pt\/wp-json\/wp\/v2\/product_cat?post=3094"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gneealloy.com\/pt\/wp-json\/wp\/v2\/product_tag?post=3094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}