{"id":4176,"date":"2025-01-23T14:14:34","date_gmt":"2025-01-23T06:14:34","guid":{"rendered":"https:\/\/gneealloy.com\/?post_type=product&#038;p=4176"},"modified":"2025-07-18T17:51:37","modified_gmt":"2025-07-18T09:51:37","slug":"inconel-718-plate-supplier","status":"publish","type":"product","link":"https:\/\/gneealloy.com\/fr\/products\/inconel-718-plate-supplier\/","title":{"rendered":"Fournisseur de plaques Inconel 718"},"content":{"rendered":"<p>La plaque Inconel 718 est un alliage nickel-chrome haute r\u00e9sistance et r\u00e9sistant \u00e0 la corrosion, offrant d&#039;excellentes performances \u00e0 haute temp\u00e9rature (jusqu&#039;\u00e0 700 \u00b0C\/1292 \u00b0F). Compos\u00e9e principalement de nickel (50-55%) et de chrome (17-21%), elle contient \u00e9galement du molybd\u00e8ne, du niobium, de l&#039;aluminium et du titane.<\/p>\n<p>L&#039;Inconel 718 est particuli\u00e8rement reconnu pour sa capacit\u00e9 \u00e0 maintenir une limite d&#039;\u00e9lasticit\u00e9 et une r\u00e9sistance \u00e0 la traction \u00e9lev\u00e9es, ainsi qu&#039;une excellente r\u00e9sistance \u00e0 la fatigue et \u00e0 l&#039;oxydation jusqu&#039;\u00e0 700 \u00b0C (1\u00a0292 \u00b0F). Il est utilis\u00e9 dans l&#039;a\u00e9rospatiale, la production d&#039;\u00e9nergie et les industries de transformation chimique pour les moteurs \u00e0 turbine, les syst\u00e8mes d&#039;\u00e9chappement et les composants haute temp\u00e9rature. Il est reconnu par les normes ASTM B637 et UNS N07718.<\/p>\n<h2>Param\u00e8tres du produit de la feuille Inconel 718<\/h2>\n<table style=\"border-collapse: collapse; width: 617.27pt;\" border=\"0\" width=\"823\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt; width: 210.00pt;\" width=\"280\" height=\"18\"><strong>Propri\u00e9t\u00e9<\/strong><\/td>\n<td class=\"et2\" style=\"width: 407.25pt;\" width=\"543\"><strong>Valeur<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\">Produit<\/td>\n<td class=\"et2\">Plaque Inconel 718<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\">Type de mat\u00e9riau<\/td>\n<td class=\"et2\">Alliage nickel-chrome<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\">Grade<\/td>\n<td class=\"et2\">Inconel 718<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\">Plage d&#039;\u00e9paisseur<\/td>\n<td class=\"et2\">0,5 mm \u2013 200 mm<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\">Plage de largeur<\/td>\n<td class=\"et2\">100 mm \u2013 2000 mm<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\">Plage de longueur<\/td>\n<td class=\"et2\">100 mm \u2013 6000 mm<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\">Standard<\/td>\n<td class=\"et2\">ASTM B637, AMS 5662, UNS N07718<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\">Composition chimique<\/td>\n<td class=\"et2\">Ni : 50-55%, Cr : 17-21%, Fe : 18-21%, Mo : 2,8-3,3%, Ti : 0,65-1,15%<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\">Densit\u00e9<\/td>\n<td class=\"et2\">8,19 g\/cm\u00b3<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\">R\u00e9sistance \u00e0 la traction<\/td>\n<td class=\"et2\">1035 MPa<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\">Limite d&#039;\u00e9lasticit\u00e9<\/td>\n<td class=\"et2\">690 MPa<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\">\u00c9longation<\/td>\n<td class=\"et2\">0.15<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\">Duret\u00e9<\/td>\n<td class=\"et2\">35-43 HRC<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\">Point de fusion<\/td>\n<td class=\"et2\">1260\u00b0C \u2013 1330\u00b0C<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\">Processus de fabrication<\/td>\n<td class=\"et2\">Laminage \u00e0 chaud, laminage \u00e0 froid, recuit<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\">Applications<\/td>\n<td class=\"et2\">A\u00e9rospatiale, turbines \u00e0 gaz, r\u00e9acteurs nucl\u00e9aires, service \u00e0 haute temp\u00e9rature<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Quelles normes ASTM de plaque Inconel 718 Gnee peut-il produire ?<\/h2>\n<table style=\"border-collapse: collapse; width: 617.27pt;\" border=\"0\" width=\"823\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt; width: 210.00pt;\" width=\"280\" height=\"18\"><strong>Norme ASTM<\/strong><\/td>\n<td style=\"width: 407.25pt;\" width=\"543\"><strong>Description<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt;\" height=\"18\">ASTM B637<\/td>\n<td>Sp\u00e9cification pour l&#039;Inconel 718, alliage durci par pr\u00e9cipitation<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt;\" height=\"18\">ASTM B705<\/td>\n<td>Sp\u00e9cifications pour les alliages de nickel, les t\u00f4les et les plaques<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt;\" height=\"18\">ASTM B751<\/td>\n<td>Sp\u00e9cification pour les alliages \u00e0 haute temp\u00e9rature<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt;\" height=\"18\">AMS 5662<\/td>\n<td>Sp\u00e9cification a\u00e9rospatiale pour l&#039;Inconel 718<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Inconel 718 Plaques et t\u00f4les Nuances \u00e9quivalentes<\/h2>\n<table style=\"border-collapse: collapse; width: 504.02pt;\" border=\"0\" width=\"672\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt; width: 126.00pt;\" width=\"168\" height=\"18\">Standard<\/td>\n<td class=\"et2\" style=\"width: 126.00pt;\" width=\"168\">UNS<\/td>\n<td class=\"et2\" style=\"width: 126.00pt;\" width=\"168\">FR<\/td>\n<td class=\"et2\" style=\"width: 126.00pt;\" width=\"168\">VACARME<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\">Inconel 718<\/td>\n<td class=\"et2\">N07718<\/td>\n<td class=\"et2\">2.4668<\/td>\n<td class=\"et2\">NiCr19FeNb<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Nous fournissons des services de traitement de surface de plaques Inconel 718<\/h2>\n<ul>\n<li data-start=\"71\" data-end=\"187\"><strong data-start=\"73\" data-end=\"97\">Recuit brillant (BA)<\/strong>:Une surface lisse et brillante avec une oxydation minimale, id\u00e9ale pour les applications hautes performances.<\/li>\n<li data-start=\"71\" data-end=\"187\"><strong data-start=\"190\" data-end=\"202\">Brillant<\/strong>:Une finition haute brillance obtenue gr\u00e2ce au polissage m\u00e9canique.<\/li>\n<li data-start=\"71\" data-end=\"187\"><strong data-start=\"265\" data-end=\"276\">marin\u00e9<\/strong>: \u00c9limination des couches de tartre et d&#039;oxyde par traitement acide pour am\u00e9liorer la qualit\u00e9 de surface.<\/li>\n<li data-start=\"71\" data-end=\"187\"><strong data-start=\"365\" data-end=\"380\">Finition du moulin<\/strong>:La surface brute et non polie issue du processus de laminage.<\/li>\n<\/ul>\n<p><span style=\"font-family: var(--global-body-font-family);\">Finitions personnalis\u00e9es adapt\u00e9es aux exigences sp\u00e9cifiques des clients<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Gnee se sp\u00e9cialise dans la production et la fourniture de I<strong>Plaque Nconel 718<\/strong> mati\u00e8res premi\u00e8res. Nos plaques sont conformes aux normes.<strong> ASTM B637<\/strong>,<strong> ASTM B705<\/strong> et d&#039;autres normes internationales et peuvent \u00eatre utilis\u00e9es pour fabriquer des \u00e9quipements tels que des r\u00e9acteurs chimiques, des \u00e9changeurs de chaleur, des syst\u00e8mes d&#039;extraction de p\u00e9trole, des composants de turbines, etc.<\/p>\n<p>Nous proposons des plaques en alliage \u00e0 base de nickel de diff\u00e9rentes tailles et d&#039;\u00e9paisseurs vari\u00e9es. <strong>3 mm \u00e0 100 mm<\/strong>, et fournir <strong>services de traitement de pr\u00e9cision<\/strong> Nous proposons des services tels que la d\u00e9coupe, l&#039;usinage et le traitement thermique. Nous fournissons \u00e9galement d&#039;autres qualit\u00e9s et formes de produits en alliage \u00e0 base de nickel. <strong>Les commandes personnalis\u00e9es sont les bienvenues<\/strong>!<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-4258 size-full\" src=\"https:\/\/gneealloy.com\/wp-content\/uploads\/2024\/12\/Certificate-1.jpg\" alt=\"Certificat\" width=\"830\" height=\"100\" srcset=\"https:\/\/gneealloy.com\/wp-content\/uploads\/2024\/12\/Certificate-1.jpg 830w, https:\/\/gneealloy.com\/wp-content\/uploads\/2024\/12\/Certificate-1-300x36.jpg 300w, https:\/\/gneealloy.com\/wp-content\/uploads\/2024\/12\/Certificate-1-768x93.jpg 768w, https:\/\/gneealloy.com\/wp-content\/uploads\/2024\/12\/Certificate-1-18x2.jpg 18w, https:\/\/gneealloy.com\/wp-content\/uploads\/2024\/12\/Certificate-1-820x100.jpg 820w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><\/p>","protected":false},"featured_media":4229,"template":"","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"default","_kad_post_title":"","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"default","_kad_post_vertical_padding":"default","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"product_brand":[],"product_cat":[83],"product_tag":[118,116],"class_list":["post-4176","product","type-product","status-publish","has-post-thumbnail","product_cat-inconel","product_tag-inconel-grade-shape","product_tag-land-page","first","instock","shipping-taxable","product-type-simple","entry","content-bg","loop-entry"],"taxonomy_info":{"product_cat":[{"value":83,"label":"Inconel"}],"product_tag":[{"value":118,"label":"Inconel Grade Shape"},{"value":116,"label":"Land Page"}]},"featured_image_src_large":["https:\/\/gneealloy.com\/wp-content\/uploads\/2025\/01\/Inconel-718-Cold-Rolled-Plate-1.jpg",800,600,false],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/gneealloy.com\/fr\/wp-json\/wp\/v2\/product\/4176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gneealloy.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gneealloy.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gneealloy.com\/fr\/wp-json\/wp\/v2\/media\/4229"}],"wp:attachment":[{"href":"https:\/\/gneealloy.com\/fr\/wp-json\/wp\/v2\/media?parent=4176"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gneealloy.com\/fr\/wp-json\/wp\/v2\/product_brand?post=4176"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gneealloy.com\/fr\/wp-json\/wp\/v2\/product_cat?post=4176"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gneealloy.com\/fr\/wp-json\/wp\/v2\/product_tag?post=4176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}