{"id":3262,"date":"2024-12-10T17:03:10","date_gmt":"2024-12-10T09:03:10","guid":{"rendered":"https:\/\/gneealloy.com\/?post_type=product&#038;p=3262"},"modified":"2026-06-23T18:02:41","modified_gmt":"2026-06-23T10:02:41","slug":"inconel-690-manufacturer","status":"publish","type":"product","link":"https:\/\/gneealloy.com\/fr\/products\/inconel-690-manufacturer\/","title":{"rendered":"Fabricant d&#039;Inconel 690"},"content":{"rendered":"<p>L&#039;Inconel 690 pr\u00e9sente une excellente r\u00e9sistance \u00e0 l&#039;oxydation \u00e0 haute temp\u00e9rature et \u00e0 la corrosion par les chlorures, notamment dans les environnements difficiles tels que ceux rencontr\u00e9s dans les proc\u00e9d\u00e9s chimiques, la p\u00e9trochimie et la production d&#039;\u00e9nergie. Cet alliage conserve ses propri\u00e9t\u00e9s m\u00e9caniques jusqu&#039;\u00e0 1\u00a0100 \u00b0C et ne s&#039;oxyde ni ne se corrode significativement \u00e0 des temp\u00e9ratures extr\u00eames. L&#039;Inconel N06690 pr\u00e9sente \u00e9galement une bonne r\u00e9sistance m\u00e9canique, une bonne t\u00e9nacit\u00e9 et une bonne soudabilit\u00e9. Sa teneur \u00e9lev\u00e9e en chrome lui conf\u00e8re non seulement une excellente r\u00e9sistance \u00e0 l&#039;oxydation, mais aussi une r\u00e9sistance \u00e0 la corrosion par les fluorures et \u00e0 la vapeur d&#039;eau \u00e0 haute temp\u00e9rature.<\/p>\n<h2>Param\u00e8tres du produit en alliage Inconel 690 (UNS N06690)<\/h2>\n<table style=\"border-collapse: collapse; width: 654.02pt;\" border=\"0\" width=\"872\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt; width: 165.75pt;\" width=\"221\" height=\"18\"><strong>Propri\u00e9t\u00e9<\/strong><\/td>\n<td class=\"et2\" style=\"width: 488.25pt;\" width=\"651\"><strong>Inconel 690<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\">Formulaires<\/td>\n<td class=\"et2\">Plaques, barres, t\u00f4les, tubes, composants forg\u00e9s<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\">Processus de fabrication<\/td>\n<td class=\"et2\">Laminage \u00e0 chaud, laminage \u00e0 froid, forgeage, soudage<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\">Densit\u00e9<\/td>\n<td class=\"et2\">8,47 g\/cm\u00b3<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\">R\u00e9sistance \u00e0 la traction<\/td>\n<td class=\"et2\">758 MPa (110 ksi)<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\">Limite d&#039;\u00e9lasticit\u00e9<\/td>\n<td class=\"et2\">310 MPa (45 ksi)<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\">\u00c9longation<\/td>\n<td class=\"et2\">30% (en longueur de jauge de 50 mm)<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\">Duret\u00e9<\/td>\n<td class=\"et2\">170 HB<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\">Temp\u00e9rature de fonctionnement<\/td>\n<td class=\"et2\">Jusqu&#039;\u00e0 1050\u00b0C (1922\u00b0F)<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\">R\u00e9sistance \u00e0 la corrosion<\/td>\n<td class=\"et2\">Excellente r\u00e9sistance \u00e0 l&#039;oxydation et \u00e0 la carburation<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\">Applications<\/td>\n<td class=\"et2\">\u00c9changeurs de chaleur, turbines \u00e0 gaz, centrales nucl\u00e9aires<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\">Service<\/td>\n<td class=\"et2\">Traitement sur mesure, d\u00e9coupe, soudage, traitement thermique<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Quelles normes ASTM pour l&#039;alliage Inconel 690 Gnee peut-elle produire\u00a0?<\/h2>\n<table style=\"border-collapse: collapse; width: 654.02pt;\" border=\"0\" width=\"872\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt; width: 165.75pt;\" width=\"221\" height=\"18\"><strong>Norme ASTM<\/strong><\/td>\n<td style=\"width: 488.25pt;\" width=\"651\"><strong>Description<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt;\" height=\"18\">ASTM B167<\/td>\n<td>Sp\u00e9cification standard pour les barres et pi\u00e8ces forg\u00e9es en Inconel 690<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt;\" height=\"18\">ASTM B168<\/td>\n<td>Sp\u00e9cification standard pour les plaques, feuilles et bandes Inconel 690<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt;\" height=\"18\">ASTM B517<\/td>\n<td>Sp\u00e9cification standard pour les tubes et tuyaux sans soudure en Inconel 690<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt;\" height=\"18\">ASTM B366<\/td>\n<td>Sp\u00e9cification standard pour les raccords Inconel 690 (coudes, t\u00e9s, etc.)<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td style=\"height: 13.50pt;\" height=\"18\">ASTM B625<\/td>\n<td>Sp\u00e9cification standard pour les tubes soud\u00e9s en Inconel 690<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Aolly 690 Notes \u00e9quivalentes<\/h2>\n<table style=\"border-collapse: collapse; width: 642.02pt;\" border=\"0\" width=\"856\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt; width: 160.50pt;\" width=\"214\" height=\"18\">STANDARD<\/td>\n<td class=\"et2\" style=\"width: 160.50pt;\" width=\"214\">UNS<\/td>\n<td class=\"et2\" style=\"width: 160.50pt;\" width=\"214\">FR<\/td>\n<td class=\"et2\" style=\"width: 160.50pt;\" width=\"214\">OUTILS N\u00b0<\/td>\n<\/tr>\n<tr style=\"height: 13.50pt;\">\n<td class=\"et2\" style=\"height: 13.50pt;\" height=\"18\">Inconel 690<\/td>\n<td class=\"et2\">N06690<\/td>\n<td class=\"et2\">2.4642<\/td>\n<td class=\"et2\">2.4642<\/td>\n<\/tr>\n<\/tbody>\n<\/table>","protected":false},"excerpt":{"rendered":"<p>Gnee est sp\u00e9cialis\u00e9e dans la production d&#039;une grande vari\u00e9t\u00e9 de pi\u00e8ces en alliage haute temp\u00e9rature Inconel 690, offrant un large \u00e9ventail de formes de produits, notamment <strong>plaques, barres, tubes, fils, bandes et pi\u00e8ces forg\u00e9es<\/strong>. Ces produits sont conformes aux normes. <strong>normes internationales<\/strong> telles que les normes ASTM B167 et ASTM B168, et sont adapt\u00e9es aux processus de fabrication exigeants tels que le traitement thermique, le formage \u00e0 froid, l&#039;usinage et le soudage.<\/p>\n<p>S&#039;appuyant sur des ann\u00e9es d&#039;exp\u00e9rience dans l&#039;industrie, les produits en alliage 690 de Gnee sont largement utilis\u00e9s dans les \u00e9quipements de base. <strong>production d&#039;\u00e9nergie nucl\u00e9aire<\/strong>, <strong>traitement chimique<\/strong>, et <strong>r\u00e9duction des \u00e9missions environnementales<\/strong>. Nous nous engageons \u00e0 fournir des services hautement flexibles et <strong>services personnalis\u00e9s<\/strong>. Que vous ayez besoin de dimensions non standard, de tol\u00e9rances sp\u00e9ciales, de conditions de traitement thermique sp\u00e9cifiques ou d&#039;exigences de performance uniques, notre \u00e9quipe technique peut travailler en \u00e9troite collaboration avec vous pour vous fournir une solution compl\u00e8te, de la s\u00e9lection des mat\u00e9riaux au support technique.<\/p>","protected":false},"featured_media":3266,"template":"","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"default","_kad_post_title":"","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"default","_kad_post_vertical_padding":"default","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"product_brand":[],"product_cat":[83],"product_tag":[105],"class_list":["post-3262","product","type-product","status-publish","has-post-thumbnail","product_cat-inconel","product_tag-inconel-grade","first","instock","shipping-taxable","product-type-simple","entry","content-bg","loop-entry"],"taxonomy_info":{"product_cat":[{"value":83,"label":"Inconel"}],"product_tag":[{"value":105,"label":"Inconel Grade"}]},"featured_image_src_large":["https:\/\/gneealloy.com\/wp-content\/uploads\/2024\/12\/Inconel-690-Pipe.jpg",800,600,false],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/gneealloy.com\/fr\/wp-json\/wp\/v2\/product\/3262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gneealloy.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gneealloy.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gneealloy.com\/fr\/wp-json\/wp\/v2\/media\/3266"}],"wp:attachment":[{"href":"https:\/\/gneealloy.com\/fr\/wp-json\/wp\/v2\/media?parent=3262"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gneealloy.com\/fr\/wp-json\/wp\/v2\/product_brand?post=3262"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gneealloy.com\/fr\/wp-json\/wp\/v2\/product_cat?post=3262"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gneealloy.com\/fr\/wp-json\/wp\/v2\/product_tag?post=3262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}